{"id":9132,"date":"2019-01-10T11:30:18","date_gmt":"2019-01-10T10:30:18","guid":{"rendered":"https:\/\/blog.fintonic.com\/?p=9132"},"modified":"2019-01-10T11:30:18","modified_gmt":"2019-01-10T10:30:18","slug":"estudios-fintonic-2019-el-consumo-de-moda-en-espana","status":"publish","type":"post","link":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/","title":{"rendered":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<blockquote>\n<ul>\n<li class=\"Citaprincipal\" style=\"text-align: left;\"><span lang=\"ES-TRAD\" style=\"font-size: 21px;\">1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos<\/span><\/li>\n<li class=\"Citaprincipal\" style=\"text-align: left;\"><span style=\"font-size: 21px;\">Gastaremos 121 \u20ac en ropa y complementos estas rebajas<\/span><\/li>\n<li class=\"Citaprincipal\" style=\"text-align: left;\"><span style=\"font-size: 21px;\">El gasto medio en las marcas del Grupo Inditex ser\u00e1 de 85 \u20ac<\/span><\/li>\n<li class=\"Citaprincipal\" style=\"text-align: left;\"><span lang=\"ES-TRAD\" style=\"font-size: 21px;\">Las rebajas tradicionales mantienen su atractivo frente al crecimiento del Black Friday<\/span><\/li>\n<\/ul>\n<\/blockquote>\n\n\n\n<!--more-->\n\n\n\n<p>La liberalizaci\u00f3n de los periodos de descuentos no impide que las rebajas de enero sigan siendo uno de los momentos clave para establecimientos de ropa y complementos. El <strong>48% de los espa\u00f1oles aprovechar\u00e1 estas fechas<\/strong> para comprar este tipo de art\u00edculos, en los que gastaremos 121 \u20ac de media, tal y como se desprende del Estudio Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d. <\/p>\n\n\n\n<p>Entre los protagonistas de la presente campa\u00f1a, el Grupo Inditex revalida un a\u00f1o m\u00e1s su liderazgo y <strong>6 de cada 10 compradores elegir\u00e1 como destino alguna de sus marcas<\/strong>, con Zara a la cabeza entre las m\u00e1s visitadas, seguida de Pull&amp;Bear y Stradivarius. De esta forma, el gigante textil se llevar\u00e1 la mayor parte del negocio de las rebajas, con un gasto medio de 85 \u20ac. <\/p>\n\n\n\n<p>El resto de la tarta se la reparten Mango, donde invertiremos una media de 47 \u20ac; el Grupo Cortefiel, con 46 \u20ac; Primark y Kiabi, con 42 \u20ac en cada caso y H&amp;M, donde destinaremos unos 41 \u20ac de media. <\/p>\n\n\n\n<p>Pero, unidas a las <strong>rebajas, tambi\u00e9n llegan las devoluciones.<\/strong> El 13% de los productos adquiridos no cumplir\u00e1n con las expectativas de los consumidores y volver\u00e1n a las tiendas. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vascos y navarros, los que m\u00e1s gastan en\nrebajas<\/h2>\n\n\n\n<p>El estudio tambi\u00e9n pone de manifiesto que el inter\u00e9s por las rebajas difiere en cada regi\u00f3n. Los <strong>vascos y navarros, con 134 y 133 \u20ac,<\/strong> respectivamente, son los que m\u00e1s presupuesto destinan a la renovaci\u00f3n de su armario. Por el contrario, castellano-leoneses, con 110 \u20ac; y riojanos, con 113 \u20ac, se muestran algo m\u00e1s conservadores en sus compras. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Las rebajas ganan la batalla al Black\nFriday<\/h2>\n\n\n\n<p>El Black Friday suma adeptos a\u00f1os tras a\u00f1o en todos los sectores, pero las rebajas tradicionales siguen siendo m\u00e1s atractivas para los consumidores de moda. De hecho, aunque cada vez es mayor el n\u00famero de marcas que lanzan promociones y descuentos en el entorno del \u201cviernes negro\u201d, <strong>el gasto medio en textil y complementos fue de 74 \u20ac<\/strong>. <\/p>\n\n\n\n<p>El <strong>Grupo Inditex, con 65 \u20ac; Mango, con 64 \u20ac y Grupo Cortefiel, con 46 \u20ac<\/strong>, se posicionan de nuevo en las primeras posiciones en t\u00e9rminos de gasto. Y cabe hacer una menci\u00f3n especial a los buenos resultados de H&amp;M en esta campa\u00f1a, que se sit\u00faa en cuarto lugar con 36 \u20ac. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/go.onelink.me\/4dGw\/9c41141b\\\"><img decoding=\"async\" src=\"https:\/\/www.fintonic.com\/wp-content\/uploads\/2018\/10\/Descargate-la-app--1024x401.png\" alt=\"\" class=\"wp-image-8785\"\/><\/a><\/figure>\n\n\n\n<p>\u00bfTienes cualquier consejo, curiosidad o pregunta que no hayamos comentado? \u00a1A qu\u00e9 esperas! Puedes ayudar a muchos usuarios que lean tu comentario en nuestro blog \ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos Gastaremos 121 \u20ac en ropa y complementos estas rebajas El gasto medio en las marcas del Grupo Inditex ser\u00e1 de 85 \u20ac Las rebajas tradicionales mantienen su atractivo frente al crecimiento del Black Friday<\/p>\n","protected":false},"author":3,"featured_media":9133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[890,773,621,891,892,893,894],"class_list":["post-9132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudios-fintonic","tag-consumo","tag-estudios-fintonic","tag-gasto-en-compras","tag-gasto-moda","tag-gasto-ropa","tag-moda","tag-tiendas-de-ropa"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d - Fintonic News<\/title>\n<meta name=\"description\" content=\"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: &quot;El consumo de moda en Espa\u00f1a&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d\" \/>\n<meta property=\"og:description\" content=\"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: &quot;El consumo de moda en Espa\u00f1a&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Fintonic News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fintonic\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-10T10:30:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge Jimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeJimenez1\" \/>\n<meta name=\"twitter:site\" content=\"@FINTONIC\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Jimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/\"},\"author\":{\"name\":\"Jorge Jimenez\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\"},\"headline\":\"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d\",\"datePublished\":\"2019-01-10T10:30:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/\"},\"wordCount\":457,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"consumo\",\"estudios fintonic\",\"gasto en compras\",\"gasto moda\",\"gasto ropa\",\"moda\",\"tiendas de ropa\"],\"articleSection\":[\"Estudios Fintonic\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/\",\"name\":\"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d - Fintonic News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-01-10T10:30:18+00:00\",\"description\":\"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: \\\"El consumo de moda en Espa\u00f1a\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"name\":\"Fintonic News\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\",\"name\":\"Fintonic News\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Fintonic News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fintonic\\\/\",\"https:\\\/\\\/x.com\\\/FINTONIC\",\"https:\\\/\\\/www.instagram.com\\\/fintonic_app\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@fintonic?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fintonic\\\/mycompany\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@fintonictv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\",\"name\":\"Jorge Jimenez\",\"description\":\"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/JorgeJimenez1\"],\"jobTitle\":\"Head of Growth\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/author\\\/jorge-jimenez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d - Fintonic News","description":"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: \"El consumo de moda en Espa\u00f1a\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/","og_locale":"es_ES","og_type":"article","og_title":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d","og_description":"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: \"El consumo de moda en Espa\u00f1a\"","og_url":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/","og_site_name":"Fintonic News","article_publisher":"https:\/\/www.facebook.com\/Fintonic\/","article_published_time":"2019-01-10T10:30:18+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","type":"image\/png"}],"author":"Jorge Jimenez","twitter_card":"summary_large_image","twitter_creator":"@JorgeJimenez1","twitter_site":"@FINTONIC","twitter_misc":{"Escrito por":"Jorge Jimenez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#article","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/"},"author":{"name":"Jorge Jimenez","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499"},"headline":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d","datePublished":"2019-01-10T10:30:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/"},"wordCount":457,"publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#primaryimage"},"thumbnailUrl":"","keywords":["consumo","estudios fintonic","gasto en compras","gasto moda","gasto ropa","moda","tiendas de ropa"],"articleSection":["Estudios Fintonic"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/","url":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/","name":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d - Fintonic News","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#primaryimage"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-01-10T10:30:18+00:00","description":"1 de cada 2 espa\u00f1oles aprovechar\u00e1 las rebajas para comprar ropa y complementos, as\u00ed es el nuevo Estudios Fintonic 2019: \"El consumo de moda en Espa\u00f1a\"","breadcrumb":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-2019-el-consumo-de-moda-en-espana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fintonic.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Estudios Fintonic 2019 \u201cEl consumo de moda en Espa\u00f1a\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.fintonic.com\/blog\/#website","url":"https:\/\/www.fintonic.com\/blog\/","name":"Fintonic News","description":"","publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fintonic.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fintonic.com\/blog\/#organization","name":"Fintonic News","url":"https:\/\/www.fintonic.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","contentUrl":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","width":512,"height":512,"caption":"Fintonic News"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fintonic\/","https:\/\/x.com\/FINTONIC","https:\/\/www.instagram.com\/fintonic_app\/","https:\/\/www.tiktok.com\/@fintonic?lang=es","https:\/\/www.linkedin.com\/company\/fintonic\/mycompany\/","https:\/\/www.youtube.com\/@fintonictv"]},{"@type":"Person","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499","name":"Jorge Jimenez","description":"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida","sameAs":["https:\/\/x.com\/JorgeJimenez1"],"jobTitle":"Head of Growth","url":"https:\/\/www.fintonic.com\/blog\/author\/jorge-jimenez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/9132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/comments?post=9132"}],"version-history":[{"count":0,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/9132\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/media?parent=9132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/categories?post=9132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/tags?post=9132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}