{"id":13550,"date":"2020-11-03T12:12:03","date_gmt":"2020-11-03T11:12:03","guid":{"rendered":"https:\/\/www.fintonic.com\/?p=13550"},"modified":"2020-11-03T12:12:03","modified_gmt":"2020-11-03T11:12:03","slug":"estudios-fintonic-evolucion-sectores-covid-19","status":"publish","type":"post","link":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/","title":{"rendered":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19"},"content":{"rendered":"\n<p>Un mes m\u00e1s os traemos los datos m\u00e1s interesantes sobre la evoluci\u00f3n de la econom\u00eda y el COVID.<\/p>\n\n\n\n<p>El servicio de comida a domicilio alcanz\u00f3 en septiembre unas ventas que triplican las cifras de hace un a\u00f1o<\/p>\n\n\n\n<p>La comida a domicilio, los negocios relacionados con la decoraci\u00f3n y mobiliario y la venta de libros son algunos de los sectores que mejor est\u00e1n sorteando la actual coyuntura e incluso registran crecimientos.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"343\" height=\"205\" src=\"\">En septiembre <strong>el servicio de comida a domicilio alcanz\u00f3 unas ventas que <\/strong><strong>triplican las cifras de hace un a\u00f1o<\/strong>, y siguen la senda de crecimiento que ha experimentado desde el inicio de la pandemia. En paralelo al aumento del volumen de negocio, se ha duplicado tambi\u00e9n el n\u00famero de consumidores que eligen esta f\u00f3rmula con respecto a 2019 y un 50% su gasto medio mensual.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><img decoding=\"async\" width=\"334\" height=\"201\" src=\"\">Los <strong>productos y servicios enfocados a la decoraci\u00f3n y mobiliario<\/strong> tambi\u00e9n se encuentran entre los que mejor resisten los embates de la pandemia, con un <strong>aumento estimado en su <\/strong><strong>actividad el pasado mes de un 39%,<\/strong> con respecto a 2019, increment\u00e1ndose un 30% el n\u00famero de compradores y un 7% el gasto medio. En este caso, se observa adem\u00e1s un alza exponencial tras el confinamiento.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><img decoding=\"async\" width=\"318\" height=\"189\" src=\"\">Por su parte, <strong>las ventas de libros y publicaciones este mes de septiembre est\u00e1n un 16% por encima de septiembre del a\u00f1o pasado<\/strong>, y cerca de las buenas cifras que se anot\u00f3 este sector en abril, en pleno confinamiento, cuando registraron un aumento superior al 80% en sus ventas con respecto al mismo mes de 2019.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Lupina Iturriaga, fundadora y Co-CEO de Fintonic<\/strong> \u201caunque en el mes de septiembre el consumo ha ca\u00eddo en torno a un 10% con respecto a agosto, tenemos que valorar el dato con moderado positivismo, pues se produce tras el periodo vacacional y en un escenario de gran incertidumbre\u201d.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/www.fintonic.com\/wp-content\/uploads\/2020\/10\/chris-liverani-dBI_My696Rk-unsplash_opt-1024x768.jpg\" alt=\"\" class=\"wp-image-13557\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Sectores que retroceden despu\u00e9s de los meses de vacaciones<\/h2>\n\n\n\n<p>Tras recuperarse t\u00edmidamente el consumo de los espa\u00f1oles en <strong>bares y restaurantes<\/strong> durante el verano (compensado tambi\u00e9n por la venta a domicilio), el mes de septiembre anot\u00f3 un descenso del 7% con respecto a agosto y supuso un 6% menos que el mismo mes del a\u00f1o anterior.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La misma l\u00ednea sigue el <strong>textil<\/strong>. Consigui\u00f3 algo de respiro con el periodo de rebajas, aunque el balance en septiembre fue un 3% menos que en agosto y un 16% m\u00e1s bajo que el a\u00f1o precedente, acusando una ca\u00edda del 20% en la cifra de compradores, as\u00ed como en el gasto medio mensual, un 6% m\u00e1s bajo.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Y junto a estas actividades, destaca el comercio dedicado a la <strong>belleza y el cuidado corporal<\/strong>, que ha conseguido recuperar del descenso de la actividad provocado por la etapa de confinamiento, aunque se encuentra m\u00e1s de un 30% por debajo de los niveles de septiembre de 2019.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Otros sectores, como el <strong>alojamiento<\/strong>, los <strong>transportes<\/strong> en general y las <strong>aerol\u00edneas<\/strong> en particular, as\u00ed como los<strong> espect\u00e1culos<\/strong> volvieron a retroceder el mes pasado tras los meses vacacionales con descensos significativos y superiores al 50% con respecto al mismo periodo de 2019. Desde Fintonic esperamos poder ir viendo poco a poco estas tendencias crecer, mientras tanto, ahora m\u00e1s que nunca, \u00a1nos ten\u00e9is para lo que necesit\u00e9is en el control de vuestra econom\u00eda dom\u00e9stica!<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.fintonic.com\/wp-content\/uploads\/2020\/01\/blog-footer-03.02.20-1024x491.gif\" alt=\"Descarga Fintonic\" class=\"wp-image-12612\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un mes m\u00e1s os traemos los datos m\u00e1s interesantes sobre la evoluci\u00f3n de la econom\u00eda y el COVID. El servicio de comida a domicilio alcanz\u00f3 en septiembre unas ventas que triplican las cifras de hace un a\u00f1o La comida a domicilio, los negocios relacionados con la decoraci\u00f3n y mobiliario y la venta de libros son [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":13559,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61,23,20],"tags":[1224,1225,1226,1227,1228,1229,1230],"class_list":["post-13550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dinero","category-estudios-fintonic","category-mundo-fintonic","tag-comida-a-domicilio","tag-decoracion","tag-gastos-en-comida-a-domicilio","tag-gastos-en-decoracion","tag-gastos-en-librs","tag-incrementos-de-gastos","tag-libros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19 - Fintonic News<\/title>\n<meta name=\"description\" content=\"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19\" \/>\n<meta property=\"og:description\" content=\"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Fintonic News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fintonic\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-03T11:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge Jimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeJimenez1\" \/>\n<meta name=\"twitter:site\" content=\"@FINTONIC\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Jimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/\"},\"author\":{\"name\":\"Jorge Jimenez\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\"},\"headline\":\"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19\",\"datePublished\":\"2020-11-03T11:12:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/\"},\"wordCount\":567,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"comida a domicilio\",\"decoracion\",\"gastos en comida a domicilio\",\"gastos en decoracion\",\"gastos en librs\",\"incrementos de gastos\",\"Libros\"],\"articleSection\":[\"Dinero\",\"Estudios Fintonic\",\"Mundo Fintonic\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/\",\"name\":\"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19 - Fintonic News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-11-03T11:12:03+00:00\",\"description\":\"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudios-fintonic-evolucion-sectores-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"name\":\"Fintonic News\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\",\"name\":\"Fintonic News\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Fintonic News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fintonic\\\/\",\"https:\\\/\\\/x.com\\\/FINTONIC\",\"https:\\\/\\\/www.instagram.com\\\/fintonic_app\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@fintonic?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fintonic\\\/mycompany\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@fintonictv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\",\"name\":\"Jorge Jimenez\",\"description\":\"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/JorgeJimenez1\"],\"jobTitle\":\"Head of Growth\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/author\\\/jorge-jimenez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19 - Fintonic News","description":"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/","og_locale":"es_ES","og_type":"article","og_title":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19","og_description":"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.","og_url":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/","og_site_name":"Fintonic News","article_publisher":"https:\/\/www.facebook.com\/Fintonic\/","article_published_time":"2020-11-03T11:12:03+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","type":"image\/png"}],"author":"Jorge Jimenez","twitter_card":"summary_large_image","twitter_creator":"@JorgeJimenez1","twitter_site":"@FINTONIC","twitter_misc":{"Escrito por":"Jorge Jimenez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#article","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/"},"author":{"name":"Jorge Jimenez","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499"},"headline":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19","datePublished":"2020-11-03T11:12:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/"},"wordCount":567,"publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#primaryimage"},"thumbnailUrl":"","keywords":["comida a domicilio","decoracion","gastos en comida a domicilio","gastos en decoracion","gastos en librs","incrementos de gastos","Libros"],"articleSection":["Dinero","Estudios Fintonic","Mundo Fintonic"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/","url":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/","name":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19 - Fintonic News","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-11-03T11:12:03+00:00","description":"\u00bfQuieres saber c\u00f3mo han evolucionado econ\u00f3micamente ciertos sectores en Espa\u00f1a durante la COVID-19? Desc\u00fabrelo en los estudios de Fintonic.","breadcrumb":{"@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.fintonic.com\/blog\/estudios-fintonic-evolucion-sectores-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fintonic.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Comida a domicilio, decoraci\u00f3n y libros, los que mejor resisten la Covid-19"}]},{"@type":"WebSite","@id":"https:\/\/www.fintonic.com\/blog\/#website","url":"https:\/\/www.fintonic.com\/blog\/","name":"Fintonic News","description":"","publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fintonic.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fintonic.com\/blog\/#organization","name":"Fintonic News","url":"https:\/\/www.fintonic.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","contentUrl":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","width":512,"height":512,"caption":"Fintonic News"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fintonic\/","https:\/\/x.com\/FINTONIC","https:\/\/www.instagram.com\/fintonic_app\/","https:\/\/www.tiktok.com\/@fintonic?lang=es","https:\/\/www.linkedin.com\/company\/fintonic\/mycompany\/","https:\/\/www.youtube.com\/@fintonictv"]},{"@type":"Person","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499","name":"Jorge Jimenez","description":"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida","sameAs":["https:\/\/x.com\/JorgeJimenez1"],"jobTitle":"Head of Growth","url":"https:\/\/www.fintonic.com\/blog\/author\/jorge-jimenez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/13550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/comments?post=13550"}],"version-history":[{"count":0,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/13550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/media?parent=13550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/categories?post=13550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/tags?post=13550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}