{"id":12816,"date":"2020-03-25T18:04:38","date_gmt":"2020-03-25T17:04:38","guid":{"rendered":"https:\/\/www.fintonic.com\/?p=12816"},"modified":"2025-03-30T23:59:20","modified_gmt":"2025-03-30T21:59:20","slug":"estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo","status":"publish","type":"post","link":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/","title":{"rendered":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo"},"content":{"rendered":"\n<p>Como hicimos la <a href=\"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-consumo-del-1-al-15-marzo\/\">pasada semana,<\/a> analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, esta vez desde el 16 hasta el 22 de marzo. Estos son algunos de los datos m\u00e1s destacados:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El 17% de los espa\u00f1oles realiz\u00f3 m\u00e1s de una compra en grandes superficies en la primera semana de cuarentena<\/li><li>Mercadona represent\u00f3 el 35% de las ventas, seguida de Carrefour con un 12%.<\/li><li>El gasto medio en la cesta de la compra fue de 80 euros.&nbsp;<\/li><\/ul>\n\n\n\n<p>Durante la primera semana de la cuarentena impuesta por la autoridades para frenar la expansi\u00f3n del Covid-19, uno de cada seis espa\u00f1oles realiz\u00f3 m\u00e1s de un compra en grandes superficies de alimentaci\u00f3n, mientras que un 35% acudi\u00f3 a estos establecimientos solo una vez en estos d\u00edas. As\u00ed se ve en el \u00faltimo estudio que desde Fintonic hemos realizado analizando los indicadores del consumo.<\/p>\n\n\n\n<p>Los datos recogidos muestran una t\u00f3nica similar en todas las regiones, aunque destaca levemente Catalu\u00f1a, donde un 22% de la poblaci\u00f3n registr\u00f3 m\u00e1s de un pago en estos comercios, seguida de Arag\u00f3n, con un 21%.&nbsp;<\/p>\n\n\n\n<p><strong>El gasto medio por espa\u00f1ol en superficies de alimentaci\u00f3n fue de 80 euros<\/strong>, lo que representa un <strong>17% menos que la semana pasada<\/strong>, aunque en comparaci\u00f3n con una semana media, supone un incremento de un 14%.&nbsp;<\/p>\n\n\n\n<p>En cuanto al reparto del mercado, <strong>Mercadona logr\u00f3 la mayor proporci\u00f3n superando el 35% de la facturaci\u00f3n total<\/strong>. Le sigue Carrefour, con un 12,16%; Lidl, con un 5,6% y Alcampo con un 4,24%.&nbsp;<\/p>\n\n\n\n<p>Cuota de mercado de las&nbsp;<strong>Grandes Superficies.<\/strong> 16\/22 de marzo de 2020<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.fintonic.com\/wp-content\/uploads\/2020\/03\/Imagen-1-1.png\" alt=\"Cuota de mercado de las Grandes Superficies. 16\/22 de marzo de 2020\" class=\"wp-image-12817\"\/><\/figure>\n\n\n\n<p>Estas cuotas de mercado que se mantienen a grandes rasgos en la misma l\u00ednea que la <a href=\"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-consumo-del-1-al-15-marzo\/\">semana anterior<\/a>. <\/p>\n\n\n\n<p>Cuota de mercado de las&nbsp;<strong>Grandes Superficies<\/strong>. 9\/15 de marzo 2020<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.fintonic.com\/wp-content\/uploads\/2020\/03\/Imagen-2-1.png\" alt=\"Cuota de mercado de las Grandes Superficies. 9\/15 de marzo 2020\" class=\"wp-image-12818\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Servicio de asesoramiento Fintonic durante la cuarentena<\/h2>\n\n\n\n<p>Tal y como venimos haciendo desde nuestro nacimiento, en&nbsp;<a href=\"https:\/\/go.onelink.me\/4dGw\/9c41141b\">Fintonic<\/a>&nbsp;queremos ayudar, y no solo a nuestros usuarios por eso si tienes cualquier duda puedes conectar con nosotros en el 911920330 (L-V 9:30 a 19:00h) o escribirnos a <a href=\"mailto:ayuda@52.210.119.160\">ayuda@52.210.119.160<\/a>. Estaremos encantados de dar respuesta y apoyo a las cuestiones que te preocupan a ti y a los tuyos. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como hicimos la pasada semana, analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, esta vez desde el 16 hasta el 22 de marzo. Estos son algunos de los datos m\u00e1s destacados: El 17% de los espa\u00f1oles realiz\u00f3 m\u00e1s de una compra en grandes superficies en la primera semana de cuarentena Mercadona [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":12824,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23,194],"tags":[1149,773,1151],"class_list":["post-12816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estudios-fintonic","category-gasto","tag-covid-19","tag-estudios-fintonic","tag-indicadores-consumo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo - Fintonic News<\/title>\n<meta name=\"description\" content=\"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo\" \/>\n<meta property=\"og:description\" content=\"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/\" \/>\n<meta property=\"og:site_name\" content=\"Fintonic News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fintonic\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-25T17:04:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-30T21:59:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"512\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Jorge Jimenez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@JorgeJimenez1\" \/>\n<meta name=\"twitter:site\" content=\"@FINTONIC\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jorge Jimenez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/\"},\"author\":{\"name\":\"Jorge Jimenez\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\"},\"headline\":\"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo\",\"datePublished\":\"2020-03-25T17:04:38+00:00\",\"dateModified\":\"2025-03-30T21:59:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/\"},\"wordCount\":368,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Covid-19\",\"estudios fintonic\",\"Indicadores Consumo\"],\"articleSection\":[\"Estudios Fintonic\",\"Gasto\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/\",\"name\":\"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo - Fintonic News\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2020-03-25T17:04:38+00:00\",\"dateModified\":\"2025-03-30T21:59:20+00:00\",\"description\":\"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"name\":\"Fintonic News\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#organization\",\"name\":\"Fintonic News\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-Fintonic_Logo-1-1.png\",\"width\":512,\"height\":512,\"caption\":\"Fintonic News\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fintonic\\\/\",\"https:\\\/\\\/x.com\\\/FINTONIC\",\"https:\\\/\\\/www.instagram.com\\\/fintonic_app\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@fintonic?lang=es\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fintonic\\\/mycompany\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@fintonictv\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/#\\\/schema\\\/person\\\/ddf97a6c293f2dbeed890d3f3d817499\",\"name\":\"Jorge Jimenez\",\"description\":\"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/JorgeJimenez1\"],\"jobTitle\":\"Head of Growth\",\"url\":\"https:\\\/\\\/www.fintonic.com\\\/blog\\\/author\\\/jorge-jimenez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo - Fintonic News","description":"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/","og_locale":"es_ES","og_type":"article","og_title":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo","og_description":"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.","og_url":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/","og_site_name":"Fintonic News","article_publisher":"https:\/\/www.facebook.com\/Fintonic\/","article_published_time":"2020-03-25T17:04:38+00:00","article_modified_time":"2025-03-30T21:59:20+00:00","og_image":[{"width":512,"height":512,"url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","type":"image\/png"}],"author":"Jorge Jimenez","twitter_card":"summary_large_image","twitter_creator":"@JorgeJimenez1","twitter_site":"@FINTONIC","twitter_misc":{"Escrito por":"Jorge Jimenez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#article","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/"},"author":{"name":"Jorge Jimenez","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499"},"headline":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo","datePublished":"2020-03-25T17:04:38+00:00","dateModified":"2025-03-30T21:59:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/"},"wordCount":368,"publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#primaryimage"},"thumbnailUrl":"","keywords":["Covid-19","estudios fintonic","Indicadores Consumo"],"articleSection":["Estudios Fintonic","Gasto"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/","url":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/","name":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo - Fintonic News","isPartOf":{"@id":"https:\/\/www.fintonic.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#primaryimage"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2020-03-25T17:04:38+00:00","dateModified":"2025-03-30T21:59:20+00:00","description":"Analizamos los principales indicadores de consumo de los espa\u00f1oles consecuencia del Covid-19, desde el 16 hasta el 22 de marzo. Descubre los resultados.","breadcrumb":{"@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.fintonic.com\/blog\/estudio-fintonic-indicadores-del-consumo-del-16-al-22-de-marzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fintonic.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Estudio Fintonic: Indicadores del Consumo del 16 al 22 de Marzo"}]},{"@type":"WebSite","@id":"https:\/\/www.fintonic.com\/blog\/#website","url":"https:\/\/www.fintonic.com\/blog\/","name":"Fintonic News","description":"","publisher":{"@id":"https:\/\/www.fintonic.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fintonic.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.fintonic.com\/blog\/#organization","name":"Fintonic News","url":"https:\/\/www.fintonic.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","contentUrl":"https:\/\/www.fintonic.com\/blog\/wp-content\/uploads\/2024\/03\/cropped-Fintonic_Logo-1-1.png","width":512,"height":512,"caption":"Fintonic News"},"image":{"@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fintonic\/","https:\/\/x.com\/FINTONIC","https:\/\/www.instagram.com\/fintonic_app\/","https:\/\/www.tiktok.com\/@fintonic?lang=es","https:\/\/www.linkedin.com\/company\/fintonic\/mycompany\/","https:\/\/www.youtube.com\/@fintonictv"]},{"@type":"Person","@id":"https:\/\/www.fintonic.com\/blog\/#\/schema\/person\/ddf97a6c293f2dbeed890d3f3d817499","name":"Jorge Jimenez","description":"Tomar buenas decisiones econ\u00f3micas es saber disfrutar la vida","sameAs":["https:\/\/x.com\/JorgeJimenez1"],"jobTitle":"Head of Growth","url":"https:\/\/www.fintonic.com\/blog\/author\/jorge-jimenez\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/12816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/comments?post=12816"}],"version-history":[{"count":2,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/12816\/revisions"}],"predecessor-version":[{"id":88807,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/posts\/12816\/revisions\/88807"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/media?parent=12816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/categories?post=12816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fintonic.com\/blog\/wp-json\/wp\/v2\/tags?post=12816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}